{"id":486,"date":"2020-04-13T16:13:18","date_gmt":"2020-04-13T14:13:18","guid":{"rendered":"http:\/\/www.johannesgelich.com\/wp\/?p=486"},"modified":"2020-04-13T16:16:05","modified_gmt":"2020-04-13T14:16:05","slug":"wer-ist-opfer-macht-und-ohnmacht-eines-rollenbildes","status":"publish","type":"post","link":"https:\/\/www.johannesgelich.com\/wp\/wer-ist-opfer-macht-und-ohnmacht-eines-rollenbildes\/","title":{"rendered":"Wer ist Opfer? Macht und Ohnmacht eines Rollenbildes"},"content":{"rendered":"<p><a href=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-300x200.jpg\" alt=\"20069-Du_Opfer\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-492\" srcset=\"https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-300x200.jpg 300w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-768x512.jpg 768w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-150x100.jpg 150w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-400x267.jpg 400w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-800x533.jpg 800w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer-200x133.jpg 200w, https:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/20069-Du_Opfer.jpg 945w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>RADIOKOLLEG, ORF, \u00d61<br \/>\n6.-9.4.2020<\/p>\n<p><strong>Gestaltung: Johannes Gelich<br \/>\n<\/strong><br \/>\nIn Zeiten von Populismus, Klimakrise, Geschlechter- und Generationenkampf geistert ein Begriff durch die einschl\u00e4gigen gesellschaftspolitischen Debatten: das Opfer. In den letzten Jahren ist, so scheint es, ein regelrechter Opfermarkt entstanden: das Volk ist Opfer einer von au\u00dfen gesteuerten Migrationspolitik, sagen rechte Populisten. Der Arbeitnehmer von heute ist Opfer der Profit-Interessen von Kapital, Konzernen und politischen Eliten auf dem Schlachtfeld des Neoliberalismus, sagen linke Populisten.<br \/>\nFrauen sind Opfer von sexistischen \u00dcbergriffen in Beruf und Medien, sagen Frauenrechtlerinnen. M\u00e4nner sind Opfer von blindw\u00fctigen Feministinnen, sagen M\u00e4nnerverb\u00e4nde. Dritte-Welt-L\u00e4nder sind Opfer neokolonialistischer Politik des reichen Westens, sagen Globalisierungskritiker. Wachstumsideologie, Umweltzerst\u00f6rung und die Ausbeutung von Ressourcen geschehen auf dem R\u00fccken der Kinder, sagen \u00d6kologen. Eltern werden von ihren Kindern in Altersheime abgeschoben und vernachl\u00e4ssigt, sagen Pensionisten-Verb\u00e4nde.<\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-486-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/opfer-rk1-EF.1304_Auswahl_2020-04-13_1518.mp3?_=1\" \/><a href=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/opfer-rk1-EF.1304_Auswahl_2020-04-13_1518.mp3\">http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/opfer-rk1-EF.1304_Auswahl_2020-04-13_1518.mp3<\/a><\/audio>\n<audio class=\"wp-audio-shortcode\" id=\"audio-486-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/RK-2-OPFER-EF-1304_Auswahl_20200413_15.22.mp3?_=2\" \/><a href=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/RK-2-OPFER-EF-1304_Auswahl_20200413_15.22.mp3\">http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/RK-2-OPFER-EF-1304_Auswahl_20200413_15.22.mp3<\/a><\/audio>\n<audio class=\"wp-audio-shortcode\" id=\"audio-486-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-opfer-t3-1304_Auswahl_2020-04-13_1537.mp3?_=3\" \/><a href=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-opfer-t3-1304_Auswahl_2020-04-13_1537.mp3\">http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-opfer-t3-1304_Auswahl_2020-04-13_1537.mp3<\/a><\/audio>\n<audio class=\"wp-audio-shortcode\" id=\"audio-486-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-4-opfer-ef_Auswahl_2020-04-13_1540.mp3?_=4\" \/><a href=\"http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-4-opfer-ef_Auswahl_2020-04-13_1540.mp3\">http:\/\/www.johannesgelich.com\/wp\/wp-content\/uploads\/2020\/04\/rk-4-opfer-ef_Auswahl_2020-04-13_1540.mp3<\/a><\/audio>\n<p><!--more--><br \/>\nDas Opfer, so viel steht fest, ist der wahre Held unserer Zeit. Opfer zu sein, verspricht h\u00f6chste Anerkennung, erzeugt machtvolle Anspr\u00fcche und ist \u00fcber jede Kritik erhaben. Doch warum und seit wann hat der Opfer-Status einen derartigen Stellenwert in der westlichen Kultur und ihren gesellschaftlichen Debatten gewonnen? Die Darbringung von Opfern gegen\u00fcber G\u00f6ttern ist ein wesentlicher Bestandteil der meisten Religionen der Welt. Doch im Christentum hat sich Gott durch seine Menschwerdung bis zu seinem Tod am Kreuz selbst geopfert. Hier zeigt sich religionsgeschichtlich insofern eine Wende, als sich Jesus f\u00fcr die S\u00fcnden der Menschen selbst opfert und damit weitere Opfer \u00fcberfl\u00fcssig macht.<\/p>\n<p>Die Anbetung des Opfers hat im Medienzeitalter jedoch eine neue, quasi-religi\u00f6se Dimension erfahren: Das Fernsehen und eine ad\u00e4quate Medien-Inszenierung leben geradezu von der Dauerpr\u00e4senz des Opfers. Von der Allgegenw\u00e4rtigkeit des Opfers von Verbrechen in Kriminalfilmen bis hin zur Akkumulation von politischem Kapital durch Fernsehbilder wie 9\/11: in den Medien ist l\u00e4ngst eine Konkurrenz um die Pr\u00e4senz der Opfer-Identit\u00e4ten entstanden. Und auch die \u00f6sterreichische Identit\u00e4t war noch lange nach dem 2. Weltkrieg von dem Mythos gepr\u00e4gt, das erste Opfer des Nationalsozialismus gewesen zu sein. Doch was sind die Auswege aus diesem sch\u00e4dlichen, medial transportierten Opfer-T\u00e4ter-Schema? Gefragt sind die St\u00e4rkung demokratischer Kr\u00e4fte und die Verantwortung jedes Einzelnen, Fakten zu studieren, L\u00f6sungsans\u00e4tze zu diskutieren und sich in demokratische Entscheidungsprozesse einzubringen. Nur so l\u00e4sst sich dieser Regress ins Primitive unterbinden.<\/p>\n<p>Literaturliste:<\/p>\n<p>Ren\u00e9 Girard, Elisabeth Mainberger-Ruh (\u00dcbers.): Das Heilige und die Gewalt,<br \/>\nPatmos Verlag, 2012.<\/p>\n<p>Matthias Lohre: Das Opfer ist der neue Held: Warum es heute Macht verleiht, sich machtlos zu geben, 288 Seiten, G\u00fctersloher Verlagshaus, 2019.<\/p>\n<p>Kirstin Breitenfellner: Wie k\u00f6nnen wir \u00fcber Opfer reden? Passagen-Verlag, 2018<br \/>\nKirstin Breitenfellner: Wir Opfer: Warum der S\u00fcndenbock unsere Kultur bestimmt, Diederichs, 2013.<\/p>\n<p>Bernhard Laum und Christina von Braun: Heiliges Geld: Eine historische Untersuchung \u00fcber den sakralen Ursprung des Geldes, Semele-Verlag, 2006.<\/p>\n<p>Peter Novick: Nach dem Holocaust. Der Umgang mit dem Massenmord (Deutsch),<br \/>\nDeutsche Verlags-Anstalt DVA, 2001.<\/p>\n<p>Kerstin Schweigh\u00f6fer (Autor), Dieter Quermann (Autor): Herzensbr\u00fcche: Geschichten von Trennungen und Neubeginn, Hoffmann und Campe Verlag, 2019.<\/p>\n<p>B\u00e4rbel Mechler: Mein (Ex-)Partner ist ein Psychopath: Wege aus der Opferfalle, Mankau Verlag, 2017.<\/p>\n<p>Matthias Dusini (Autor), Thomas Edlinger (Autor): Glanz und Elend der Political Correctness, edition suhrkamp, Suhrkamp Verlag, 2012.<br \/>\nHOTLINES:<\/p>\n<p>M\u00e4nnerberatung Wien 01 6032828<\/p>\n<p>Jugendanwaltschaft Wien<br \/>\nMag. Ercan Nik Nafs<br \/>\nTel.: 01\/70 77 000<\/p>\n<p>Frauenberatung Wien<br \/>\nTerminvereinbarung und Beratungstelefon: 587 67 50<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RADIOKOLLEG, ORF, \u00d61 6.-9.4.2020 Gestaltung: Johannes Gelich In Zeiten von Populismus, Klimakrise, Geschlechter- und Generationenkampf geistert ein Begriff durch die einschl\u00e4gigen gesellschaftspolitischen Debatten: das Opfer. In den letzten Jahren ist, so scheint es, ein regelrechter Opfermarkt entstanden: das Volk ist Opfer einer von au\u00dfen gesteuerten Migrationspolitik, sagen rechte Populisten. Der Arbeitnehmer von heute ist Opfer&#8230; <a class=\"more-link\" href=\"https:\/\/www.johannesgelich.com\/wp\/wer-ist-opfer-macht-und-ohnmacht-eines-rollenbildes\/\">Continue reading <span class=\"meta-nav\">&#8594;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/posts\/486"}],"collection":[{"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":4,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/posts\/486\/revisions"}],"predecessor-version":[{"id":495,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/posts\/486\/revisions\/495"}],"wp:attachment":[{"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/categories?post=486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johannesgelich.com\/wp\/wp-json\/wp\/v2\/tags?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}